{"id":20383,"date":"2017-03-04T22:45:21","date_gmt":"2017-03-05T06:45:21","guid":{"rendered":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300.jpg"},"modified":"2017-03-04T22:45:53","modified_gmt":"2017-03-05T06:45:53","slug":"49693885-young-beautiful-woman-enjoying-massage-on-the-table-at-spa-center-2","status":"inherit","type":"attachment","link":"https:\/\/energylifesciences.com\/es\/treatments\/49693885-young-beautiful-woman-enjoying-massage-on-the-table-at-spa-center-2\/","title":{"rendered":""},"author":11,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-20383","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300.jpg 300w, https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-150x150.jpg 150w, https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-125x125.jpg 125w, https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-30x30.jpg 30w, https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-250x250.jpg 250w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":300,"height":300,"file":"2016\/06\/Energy_Life_Sciences-Massage_300x300.jpg","sizes":{"thumbnail":{"file":"Energy_Life_Sciences-Massage_300x300-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-150x150.jpg"},"post-thumbnail":{"file":"Energy_Life_Sciences-Massage_300x300-125x125.jpg","width":125,"height":125,"mime_type":"image\/jpeg","source_url":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-125x125.jpg"},"sow-carousel-default":{"file":"Energy_Life_Sciences-Massage_300x300-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-272x182.jpg"},"cc-gallery-thumb":{"file":"Energy_Life_Sciences-Massage_300x300-30x30.jpg","width":30,"height":30,"mime_type":"image\/jpeg","source_url":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-30x30.jpg"},"cc-gallery-full":{"file":"Energy_Life_Sciences-Massage_300x300-250x250.jpg","width":250,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300-250x250.jpg"},"full":{"file":"Energy_Life_Sciences-Massage_300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"49693885 - young beautiful woman enjoying massage on the table at spa center","created_timestamp":"0","copyright":"hedgehog\/123RF","focal_length":"0","iso":"0","shutter_speed":"0","title":"49693885 - young beautiful woman enjoying massage on the table at spa center","orientation":"1","keywords":["massage","woman","fingers","healer","treatment","spa","stone","elbows","hands","arms","black","towel","female","closeup","lying","young","care","body","oil","serenity","beauty","skin","beautiful","health","relaxation","white","person","lady","decoration","down","horizontal","happiness","adult","therapist","caucasian","luxury","rubbing","pampering","brunette","pretty","massaging","medicine","lifestyle","healthy","enjoyment","lifestyles","indoors","healthcare","relaxing","back"]}},"post":61,"source_url":"https:\/\/energylifesciences.com\/wp-content\/uploads\/2016\/06\/Energy_Life_Sciences-Massage_300x300.jpg","filename":"Energy_Life_Sciences-Massage_300x300.jpg","filesize":79683,"_links":{"self":[{"href":"https:\/\/energylifesciences.com\/es\/wp-json\/wp\/v2\/media\/20383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/energylifesciences.com\/es\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/energylifesciences.com\/es\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/energylifesciences.com\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/energylifesciences.com\/es\/wp-json\/wp\/v2\/comments?post=20383"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":61,"href":"https:\/\/energylifesciences.com\/es\/wp-json\/wp\/v2\/pages\/61"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}